{"id":2212,"date":"2019-02-07T10:56:14","date_gmt":"2019-02-07T10:56:14","guid":{"rendered":"http:\/\/www.borros.cat\/project\/stel-puigcerda\/"},"modified":"2025-10-10T08:33:01","modified_gmt":"2025-10-10T08:33:01","slug":"stel-puigcerda","status":"publish","type":"dt_portfolio","link":"https:\/\/www.borros.cat\/es\/project\/stel-puigcerda\/","title":{"rendered":"BUNGALOWS STEL PUIGCERD\u00c0"},"content":{"rendered":"<p>Proyecto de reforma de cuatro bungalows del Camping Stel de Puigcerd\u00e0 donde hemos reconvertido los bungalows existentes en un espacio de monta\u00f1a, moderno y adaptado a todas las comodidades, la reforma ha supuesto la resdistribucion de ba\u00f1os y cocina e la selecci\u00f3n de todos los nuevos revestimientos, pavimentos y elementos decorativos para hacer del nuevo espacio m\u00e1s c\u00f3modo, c\u00e1lido y moderno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proyecto de reforma de cuatro bungalows del Camping Stel de Puigcerd\u00e0 donde hemos reconvertido los bungalows existentes en un espacio de monta\u00f1a, moderno y adaptado a todas las comodidades, la reforma ha supuesto la resdistribucion de ba\u00f1os y cocina e la selecci\u00f3n de todos los nuevos revestimientos, pavimentos y elementos decorativos para hacer del nuevo&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2216,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[12,28],"dt_portfolio_tags":[],"class_list":["post-2212","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-comercial-es","dt_portfolio_category-hospitality-es","dt_portfolio_category-12","dt_portfolio_category-28","description-off"],"_links":{"self":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio\/2212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/comments?post=2212"}],"version-history":[{"count":4,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio\/2212\/revisions"}],"predecessor-version":[{"id":7549,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio\/2212\/revisions\/7549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/media\/2216"}],"wp:attachment":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/media?parent=2212"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio_category?post=2212"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio_tags?post=2212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}