{"id":6415,"date":"2025-03-11T09:32:12","date_gmt":"2025-03-11T09:32:12","guid":{"rendered":"https:\/\/www.borros.cat\/project\/espai-gracia\/"},"modified":"2025-10-10T07:01:56","modified_gmt":"2025-10-10T07:01:56","slug":"espai-gracia","status":"publish","type":"dt_portfolio","link":"https:\/\/www.borros.cat\/es\/project\/espai-gracia\/","title":{"rendered":"ESPACIO GRACIA"},"content":{"rendered":"\n<p>La Fundaci\u00f3n Catalunya la Pedrera nos encarg\u00f3 en 2024 la creaci\u00f3n de la nueva imagen de los espacios para el envejecimiento digno que acogen las diferentes actividades del programa por personas con problemas cognitivos.<\/p>\n\n<p>\u00c9ste es el primero de una serie de espacios que han sido dise\u00f1ados para acoger a personas con deficiencias congitivas, por lo que se han escogido pavimentos y revestimientos luminosos, acabados en curva, uniformidad en colores y pocos contrastes, creando unos espacios elegantes, relajantes y duraderos en el tiempo.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n Catalunya la Pedrera nos encarg\u00f3 en 2024 la creaci\u00f3n de la nueva imagen de los espacios para el envejecimiento digno que acogen las diferentes actividades del programa por personas con problemas cognitivos. \u00c9ste es el primero de una serie de espacios que han sido dise\u00f1ados para acoger a personas con deficiencias congitivas, por&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6310,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[12],"dt_portfolio_tags":[],"class_list":["post-6415","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-comercial-es","dt_portfolio_category-12","description-off"],"_links":{"self":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio\/6415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/comments?post=6415"}],"version-history":[{"count":3,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio\/6415\/revisions"}],"predecessor-version":[{"id":6423,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio\/6415\/revisions\/6423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/media\/6310"}],"wp:attachment":[{"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/media?parent=6415"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio_category?post=6415"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/www.borros.cat\/es\/wp-json\/wp\/v2\/dt_portfolio_tags?post=6415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}